{"id":4241,"date":"2016-08-13T09:13:34","date_gmt":"2016-08-13T09:13:34","guid":{"rendered":"https:\/\/circufash.eu\/a-propos-de-nous\/"},"modified":"2026-04-25T10:07:14","modified_gmt":"2026-04-25T10:07:14","slug":"a-propos-de-nous","status":"publish","type":"page","link":"https:\/\/circufash.eu\/fr\/a-propos-de-nous\/","title":{"rendered":"\u00c0 propos"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row padding_top_multiplier=\u00a0\u00bb5x\u00a0\u00bb padding_bottom_multiplier=\u00a0\u00bb\u00a0\u00bb][vc_column text_align=\u00a0\u00bbcenter\u00a0\u00bb]<h2 class=\"eut-element eut-title eut-align-center eut-h2\" style=\"\"><span><br>\n<h1><span style=\"color: #f8522f;\">Qu\u2019est-ce que CIRCUFash ?<\/span><\/h1>\n<\/span><\/h2>[\/vc_column][\/vc_row][vc_row padding_bottom_multiplier=\u00a0\u00bb3x\u00a0\u00bb][vc_column text_align=\u00a0\u00bbcenter\u00a0\u00bb][vc_column_text css=\u00a0\u00bb\u00a0\u00bb text_style=\u00a0\u00bbleader-text\u00a0\u00bb]<\/p>\n<h6><span style=\"color: #9d9d9d;\">Le projet s&rsquo;inscrit dans les objectifs de l&rsquo;UE visant \u00e0 favoriser l&rsquo;inclusion sociale et la durabilit\u00e9 dans la mode. En \u00e9tablissant des partenariats en <strong>France<\/strong>, en <strong>Gr\u00e8ce<\/strong>, en <strong>Roumanie<\/strong> et aux <strong>Pays-Bas<\/strong>, CIRCUFash cr\u00e9e un impact durable tant au niveau local qu&rsquo;\u00e0 l&rsquo;\u00e9chelle europ\u00e9enne. L\u2019initiative soutient \u00e9galement la durabilit\u00e9 en utilisant des mat\u00e9riaux recycl\u00e9s, abordant ainsi les d\u00e9fis environnementaux en parall\u00e8le des d\u00e9fis sociaux. Cofinanc\u00e9 par la Commission europ\u00e9enne, CIRCUFash est un mod\u00e8le de collaboration transnationale innovante.. <\/span><\/h6>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row padding_top_multiplier=\u00a0\u00bb\u00a0\u00bb padding_bottom_multiplier=\u00a0\u00bb\u00a0\u00bb][vc_column]<div class=\"eut-element eut-divider\" style=\"\"><div class=\"eut-line-divider eut-border\"><\/div><\/div>[\/vc_column][\/vc_row][vc_row padding_top_multiplier=\u00a0\u00bb3x\u00a0\u00bb padding_bottom_multiplier=\u00a0\u00bb\u00a0\u00bb][vc_column width=\u00a0\u00bb1\/6&Prime; tablet_sm_width=\u00a0\u00bbhide\u00a0\u00bb mobile_width=\u00a0\u00bbhide\u00a0\u00bb][\/vc_column][vc_column width=\u00a0\u00bb2\/3&Prime; tablet_sm_width=\u00a0\u00bb1&Prime;]<h2 class=\"eut-element eut-title eut-align-center eut-h2\" style=\"\"><span>Principales composantes du projet<\/span><\/h2>[\/vc_column][vc_column width=\u00a0\u00bb1\/6&Prime; tablet_sm_width=\u00a0\u00bbhide\u00a0\u00bb mobile_width=\u00a0\u00bbhide\u00a0\u00bb][\/vc_column][\/vc_row][vc_row padding_top_multiplier=\u00a0\u00bb2x\u00a0\u00bb padding_bottom_multiplier=\u00a0\u00bb4x\u00a0\u00bb][vc_column width=\u00a0\u00bb1\/3&Prime;]<div class=\"eut-empty-space eut-height-2x\" style=\"\"><\/div><h5 class=\"eut-element eut-title eut-align-left eut-link-text\" style=\"\"><span>01 | <span class=\"eut-text-primary-1\">Portail de science citoyenne<\/span><\/span><\/h5>[vc_column_text css=\u00a0\u00bb\u00a0\u00bb]Plateforme num\u00e9rique pour la collecte de donn\u00e9es et l\u2019engagement communautaire[\/vc_column_text][\/vc_column][vc_column width=\u00a0\u00bb1\/3&Prime;]<div class=\"eut-empty-space eut-height-2x\" style=\"\"><\/div><h5 class=\"eut-element eut-title eut-align-left eut-link-text\" style=\"\"><span>02 | <span class=\"eut-text-primary-1\">Laboratoires de mode urbaine<\/span><\/span><\/h5>[vc_column_text css=\u00a0\u00bb\u00a0\u00bb]Projets pilotes de production physique dans les villes partenaires.[\/vc_column_text][\/vc_column][vc_column width=\u00a0\u00bb1\/3&Prime;]<div class=\"eut-empty-space eut-height-2x\" style=\"\"><\/div><h5 class=\"eut-element eut-title eut-align-left eut-link-text\" style=\"\"><span>03 | <span class=\"eut-text-primary-1\">Programme de formation professionnelle circulaire.<\/span><\/span><\/h5>[vc_column_text css=\u00a0\u00bb\u00a0\u00bb]Modules de formation pour les \u00e9ducateurs et les apprenants marginalis\u00e9s.[\/vc_column_text][\/vc_column][vc_column width=\u00a0\u00bb1\/3&Prime;]<div class=\"eut-empty-space eut-height-2x\" style=\"\"><\/div><h5 class=\"eut-element eut-title eut-align-left eut-link-text\" style=\"\"><span>04 | <span class=\"eut-text-primary-1\">Cartographie et consultation des PME.<\/span><\/span><\/h5>[vc_column_text css=\u00a0\u00bb\u00a0\u00bb]Soutien strat\u00e9gique pour 25 entreprises par pays.[\/vc_column_text][\/vc_column][vc_column width=\u00a0\u00bb1\/3&Prime;]<div class=\"eut-empty-space eut-height-2x\" style=\"\"><\/div><h5 class=\"eut-element eut-title eut-align-left eut-link-text\" style=\"\"><span>05 | <span class=\"eut-text-primary-1\">Collections capsules pilotes.<\/span><\/span><\/h5>[vc_column_text css=\u00a0\u00bb\u00a0\u00bb]5 r\u00e9sultats tangibles de la fabrication circulaire.[\/vc_column_text][\/vc_column][vc_column width=\u00a0\u00bb1\/3&Prime;]<div class=\"eut-empty-space eut-height-2x\" style=\"\"><\/div><h5 class=\"eut-element eut-title eut-align-left eut-link-text\" style=\"\"><span>06 | <span class=\"eut-text-primary-1\">Livre blanc sur les politiques.<\/span><\/span><\/h5>[vc_column_text css=\u00a0\u00bb\u00a0\u00bb]Outil de plaidoyer pour une fabrication circulaire inclusive.[\/vc_column_text][\/vc_column][\/vc_row][vc_row padding_top_multiplier=\u00a0\u00bb\u00a0\u00bb padding_bottom_multiplier=\u00a0\u00bb\u00a0\u00bb][vc_column]<div class=\"eut-element eut-divider\" style=\"\"><div class=\"eut-line-divider eut-border\"><\/div><\/div>[\/vc_column][\/vc_row][vc_row section_type=\u00a0\u00bbfullwidth\u00a0\u00bb bg_type=\u00a0\u00bbcolor\u00a0\u00bb padding_top_multiplier=\u00a0\u00bb\u00a0\u00bb padding_bottom_multiplier=\u00a0\u00bb\u00a0\u00bb columns_gap=\u00a0\u00bbnone\u00a0\u00bb bg_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb][vc_column]<div class=\"eut-element eut-image eut-animated-item eut-fade-in-up eut-duration-normal eut-align-center eut-full-image eut-image-space-100\" style=\"\" data-delay=\"200\">  <div class=\"eut-image-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"2400\" height=\"1350\" src=\"https:\/\/circufash.eu\/wp-content\/uploads\/2026\/04\/Atelier_1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/circufash.eu\/wp-content\/uploads\/2026\/04\/Atelier_1.jpg 2400w, https:\/\/circufash.eu\/wp-content\/uploads\/2026\/04\/Atelier_1-300x169.jpg 300w, https:\/\/circufash.eu\/wp-content\/uploads\/2026\/04\/Atelier_1-1024x576.jpg 1024w, https:\/\/circufash.eu\/wp-content\/uploads\/2026\/04\/Atelier_1-768x432.jpg 768w, https:\/\/circufash.eu\/wp-content\/uploads\/2026\/04\/Atelier_1-1536x864.jpg 1536w, https:\/\/circufash.eu\/wp-content\/uploads\/2026\/04\/Atelier_1-1170x658.jpg 1170w, https:\/\/circufash.eu\/wp-content\/uploads\/2026\/04\/Atelier_1-1920x1080.jpg 1920w\" sizes=\"auto, (max-width: 2400px) 100vw, 2400px\" \/>   <\/div><\/div>[\/vc_column][\/vc_row][vc_row padding_top_multiplier=\u00a0\u00bb2x\u00a0\u00bb][vc_column width=\u00a0\u00bb1\/6&Prime;][\/vc_column][vc_column width=\u00a0\u00bb2\/3&Prime;]<h2 class=\"eut-element eut-title eut-align-left eut-h2\" style=\"\"><span><br>\n<h2>Les <span style=\"color: #f8522f;\">groupes cibles<\/span><\/h2>\n<\/span><\/h2><div class=\"eut-empty-space eut-height-2x\" style=\"\"><\/div>[vc_row_inner][vc_column_inner width=\u00a0\u00bb1\/2&Prime;]<h3 class=\"eut-element eut-title eut-align-left eut-h6\" style=\"\"><span>Groupes cibles principaux<\/span><\/h3>[vc_column_text css=\u00a0\u00bb\u00a0\u00bb]\u25cf Communaut\u00e9s marginalis\u00e9es : R\u00e9fugi\u00e9s, migrants et survivantes de violences, en particulier les femmes (b\u00e9n\u00e9ficiaires des WP2\/WP3).<br \/>\n\u25cf \u00c9ducateurs et \u00e9tudiants de l\u2019EFTP : \u00c9coles de mode et centres de formation.<br \/>\n\u25cf PME et micro-entrepreneurs : Petites unit\u00e9s de fabrication recherchant des mod\u00e8les circulaires, 20 entreprises cartographi\u00e9es par pays recherchant des transitions circulaires.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=\u00a0\u00bb1\/2&Prime;]<h3 class=\"eut-element eut-title eut-align-left eut-h6\" style=\"\"><span>Groupes cibles secondaires<\/span><\/h3>[vc_column_text css=\u00a0\u00bb\u00a0\u00bb]\u25cf Consommateurs conscients : Individus int\u00e9ress\u00e9s par le mouvement #WhoMadeMyClothes Fashion Revolution.<br \/>\n\u25cf Autorit\u00e9s locales : Municipalit\u00e9s et agences de d\u00e9veloppement r\u00e9gional.<br \/>\n\u25cf D\u00e9cideurs politiques de l\u2019UE : Membres du Parlement europ\u00e9en et groupes de travail sur l\u2019\u00e9conomie circulaire.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=\u00a0\u00bb1\/2&Prime;]<div class=\"eut-empty-space eut-height-1x\" style=\"\"><\/div><h3 class=\"eut-element eut-title eut-align-left eut-h6\" style=\"\"><span>R\u00f4le des groupes cibles<\/span><\/h3>[vc_column_text css=\u00a0\u00bb\u00a0\u00bb]Les <strong>groupes cibles principaux<\/strong> devraient \u00eatre les participants directs, les utilisateurs et les b\u00e9n\u00e9ficiaires de la formation \u00e0 la fabrication circulaire du projet, du Centre de science citoyenne et des modules d\u2019apprentissage de l\u2019EFTP. Ils jouent un r\u00f4le actif dans le test de l\u2019approche p\u00e9dagogique du projet et la fourniture de donn\u00e9es pour la recherche sur les d\u00e9chets textiles.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=\u00a0\u00bb1\/2&Prime;]<div class=\"eut-empty-space eut-height-1x\" style=\"\"><\/div><h3 class=\"eut-element eut-title eut-align-left eut-h6\" style=\"\"><span>R\u00f4le des groupes cibles<\/span><\/h3>[vc_column_text css=\u00a0\u00bb\u00a0\u00bb]Les <strong>groupes cibles secondaires<\/strong> \u2014 y compris les Laboratoires de mode urbaine \u00e9tablis, les PME et les autorit\u00e9s locales \u2014 agissent en tant que soutiens strat\u00e9giques, multiplicateurs et d\u00e9cideurs. Leur implication est cruciale pour l\u2019int\u00e9gration au march\u00e9 des collections pilotes, la durabilit\u00e9 \u00e0 long terme du mod\u00e8le de fabrication d\u00e9centralis\u00e9 et l\u2019adoption effective des recommandations politiques du projet aux niveaux r\u00e9gional et europ\u00e9en.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column width=\u00a0\u00bb1\/6&Prime;][\/vc_column][\/vc_row][vc_row padding_top_multiplier=\u00a0\u00bb\u00a0\u00bb padding_bottom_multiplier=\u00a0\u00bb\u00a0\u00bb][vc_column]<div class=\"eut-element eut-divider\" style=\"\"><div class=\"eut-line-divider eut-border\"><\/div><\/div>[\/vc_column][\/vc_row][vc_row padding_top_multiplier=\u00a0\u00bb4x\u00a0\u00bb padding_bottom_multiplier=\u00a0\u00bb\u00a0\u00bb row_title=\u00a0\u00bbthe-partners\u00a0\u00bb][vc_column width=\u00a0\u00bb1\/3&Prime; text_align=\u00a0\u00bbcenter\u00a0\u00bb][\/vc_column][vc_column width=\u00a0\u00bb1\/3&Prime; text_align=\u00a0\u00bbcenter\u00a0\u00bb][vc_column_text css=\u00a0\u00bb.vc_custom_1776629585740{margin-bottom: 18px !important;}\u00a0\u00bb]<\/p>\n<h2 id=\"the-partners\" style=\"text-align: center;\">LES PARTENAIRES<\/h2>\n<p>[\/vc_column_text][\/vc_column][vc_column width=\u00a0\u00bb1\/3&Prime; text_align=\u00a0\u00bbcenter\u00a0\u00bb][\/vc_column][\/vc_row][vc_row columns_gap=\u00a0\u00bb50&Prime;][vc_column width=\u00a0\u00bb1\/3&Prime; css=\u00a0\u00bb.vc_custom_1776594362739{padding-right: 10% !important;padding-left: 10% !important;}\u00a0\u00bb]<div class=\"eut-element eut-image eut-animated-item eut-fade-in-up eut-duration-normal eut-align-center\" style=\"margin-bottom: 0px;\" data-delay=\"400\">  <div class=\"eut-image-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"195\" height=\"195\" src=\"https:\/\/circufash.eu\/wp-content\/uploads\/2026\/04\/Amfi_home-copie.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/circufash.eu\/wp-content\/uploads\/2026\/04\/Amfi_home-copie.png 1x,https:\/\/circufash.eu\/wp-content\/uploads\/2026\/04\/Amfi_home.png 2x\" \/>   <\/div><\/div><h3 class=\"eut-element eut-title eut-align-center eut-animated-item eut-fade-in-up eut-duration-normal eut-h5\" style=\"\" data-delay=\"600\"><span>AMFI<\/span><\/h3>[vc_column_text css=\u00a0\u00bb.vc_custom_1776625371988{margin-bottom: 30px !important;}\u00a0\u00bb animation=\u00a0\u00bbeut-fade-in-up\u00a0\u00bb]<\/p>\n<p class=\"p1\" style=\"text-align: left;\">L\u2019Amsterdam Fashion Institute (AMFI) est le plus grand institut de mode des Pays-Bas et unique en son genre : c\u2019est la seule institution \u00e9ducative qui r\u00e9unit toutes les parties de la cha\u00eene de la mode sous un m\u00eame toit. Nous rassemblons la cr\u00e9ativit\u00e9, la technologie et l\u2019entrepreneuriat. Chaque ann\u00e9e, nous formons plus de 1 500 \u00e9tudiants \u00e0 devenir des professionnels de la mode capables d\u2019avoir un impact, tant \u00e0 l\u2019int\u00e9rieur qu\u2019\u00e0 l\u2019ext\u00e9rieur de l\u2019industrie.  <\/p>\n<p>[\/vc_column_text]<div class=\"eut-element eut-align-center\"><a href=\"https:\/\/amfi.nl\/\" target=\"_blank\" rel=\"nofollow\" class=\"eut-btn eut-btn-extrasmall eut-square eut-bg-grey eut-bg-hover-primary-1\"><span>En savoir plus<\/span><\/a><\/div>[\/vc_column][vc_column width=\u00a0\u00bb1\/3&Prime; text_align=\u00a0\u00bbcenter\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1776004858521{padding-right: 10% !important;padding-left: 10% !important;}\u00a0\u00bb]<div class=\"eut-element eut-image eut-animated-item eut-fade-in-up eut-duration-normal eut-align-center\" style=\"margin-bottom: 0px;\" data-delay=\"600\">  <div class=\"eut-image-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"195\" height=\"195\" src=\"https:\/\/circufash.eu\/wp-content\/uploads\/2026\/04\/Cedecs_home-copie.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/circufash.eu\/wp-content\/uploads\/2026\/04\/Cedecs_home-copie.png 1x,https:\/\/circufash.eu\/wp-content\/uploads\/2026\/04\/Cedecs_home.png 2x\" \/>   <\/div><\/div><h3 class=\"eut-element eut-title eut-align-center eut-animated-item eut-fade-in-up eut-duration-normal eut-h5\" style=\"\" data-delay=\"600\"><span>Cedecs\u2013TCBL<\/span><\/h3>[vc_column_text css=\u00a0\u00bb.vc_custom_1776626110698{margin-bottom: 30px !important;}\u00a0\u00bb text_style=\u00a0\u00bbleader-text\u00a0\u00bb animation=\u00a0\u00bbeut-fade-in-up\u00a0\u00bb]<\/p>\n<p class=\"p1\" style=\"text-align: left;\">Cedecs-TCBL est une soci\u00e9t\u00e9 de consultants europ\u00e9ens sp\u00e9cialis\u00e9e dans l\u2019organisation et la gestion de l\u2019innovation pour les projets europ\u00e9ens de R&amp;D textile-habillement.<br \/>\nDepuis 2024, elle s\u2019appuie sur une \u00e9quipe multidisciplinaire et multinationale d\u2019experts associ\u00e9s.<br \/>\nL\u2019\u00e9quipe comprend 20 consultants seniors et exp\u00e9riment\u00e9s, de 10 nationalit\u00e9s diff\u00e9rentes, avec des profils vari\u00e9s : \u00e9conomistes, urbanistes, designers, managers, entrepreneurs, fabricants, etc.<br \/>\nCedecs-TCBL d\u00e9veloppe des r\u00e9seaux europ\u00e9ens d\u2019innovation durable, transforme ces r\u00e9seaux en \u00e9cosyst\u00e8mes durables, et facilite la formation de nouveaux entrepreneurs.[\/vc_column_text]<div class=\"eut-element eut-align-center\"><a href=\"https:\/\/www.cedecs-tcbl.com\/\" target=\"_blank\" rel=\"nofollow\" class=\"eut-btn eut-btn-extrasmall eut-square eut-bg-grey eut-bg-hover-primary-1\"><span>En savoir plus<\/span><\/a><\/div>[\/vc_column][vc_column width=\u00a0\u00bb1\/3&Prime; text_align=\u00a0\u00bbcenter\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1776004848207{padding-right: 10% !important;padding-left: 10% !important;}\u00a0\u00bb]<div class=\"eut-element eut-image eut-animated-item eut-fade-in-up eut-duration-normal eut-align-center\" style=\"margin-bottom: 0px;\" data-delay=\"600\">  <div class=\"eut-image-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"195\" height=\"195\" src=\"https:\/\/circufash.eu\/wp-content\/uploads\/2026\/04\/FRF_home-copie.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/circufash.eu\/wp-content\/uploads\/2026\/04\/FRF_home-copie.png 1x,https:\/\/circufash.eu\/wp-content\/uploads\/2026\/04\/FRF_home.png 2x\" \/>   <\/div><\/div><h3 class=\"eut-element eut-title eut-align-center eut-animated-item eut-fade-in-up eut-duration-normal eut-h5\" style=\"\" data-delay=\"800\"><span>Fashion Revolution France<\/span><\/h3>[vc_column_text css=\u00a0\u00bb.vc_custom_1776625586741{margin-bottom: 30px !important;}\u00a0\u00bb text_style=\u00a0\u00bbleader-text\u00a0\u00bb animation=\u00a0\u00bbeut-fade-in-up\u00a0\u00bb]<\/p>\n<p class=\"p1\" style=\"text-align: left;\">Fond\u00e9e au lendemain de l\u2019effondrement du Rana Plaza \u2014 le 24 avril 2013 \u2014 \u00e0 Dhaka, au Bangladesh, l\u2019ONG Fashion Revolution milite pour un syst\u00e8me de mode propre, s\u00fbr, \u00e9quitable, transparent et responsable par la recherche, l\u2019\u00e9ducation et le plaidoyer. Mouvement mondial actif dans 80 pays, Fashion Revolution partage une vision collective d\u2019une industrie de la mode qui pr\u00e9serve et restaure l\u2019environnement et valorise les personnes avant la croissance et le profit. <\/p>\n<p>[\/vc_column_text]<div class=\"eut-element eut-align-center\"><a href=\"https:\/\/www.fashionrevolution.org\/\" target=\"_blank\" rel=\"nofollow\" class=\"eut-btn eut-btn-extrasmall eut-square eut-bg-grey eut-bg-hover-primary-1\"><span>En savoir plus<\/span><\/a><\/div>[\/vc_column][\/vc_row][vc_row padding_top_multiplier=\u00a0\u00bb\u00a0\u00bb padding_bottom_multiplier=\u00a0\u00bb\u00a0\u00bb][vc_column]<div class=\"eut-element eut-divider\" style=\"\"><div class=\"eut-line-divider eut-border\"><\/div><\/div>[\/vc_column][\/vc_row][vc_row padding_top_multiplier=\u00a0\u00bb\u00a0\u00bb padding_bottom_multiplier=\u00a0\u00bb6x\u00a0\u00bb columns_gap=\u00a0\u00bb50&Prime;][vc_column width=\u00a0\u00bb1\/3&Prime; css=\u00a0\u00bb.vc_custom_1776594452505{padding-right: 10% !important;padding-left: 10% !important;}\u00a0\u00bb]<div class=\"eut-element eut-image eut-animated-item eut-fade-in-up eut-duration-normal eut-align-center eut-full-image eut-image-space-100\" style=\"margin-bottom: 0px;\" data-delay=\"400\">  <div class=\"eut-image-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"560\" height=\"560\" src=\"https:\/\/circufash.eu\/wp-content\/uploads\/2026\/04\/Soffa_sq5-560x560.jpg\" class=\"attachment-fildisi-eutf-small-square size-fildisi-eutf-small-square\" alt=\"\" srcset=\"https:\/\/circufash.eu\/wp-content\/uploads\/2026\/04\/Soffa_sq5-560x560.jpg 560w, https:\/\/circufash.eu\/wp-content\/uploads\/2026\/04\/Soffa_sq5-300x300.jpg 300w, https:\/\/circufash.eu\/wp-content\/uploads\/2026\/04\/Soffa_sq5-1024x1024.jpg 1024w, https:\/\/circufash.eu\/wp-content\/uploads\/2026\/04\/Soffa_sq5-150x150.jpg 150w, https:\/\/circufash.eu\/wp-content\/uploads\/2026\/04\/Soffa_sq5-768x768.jpg 768w, https:\/\/circufash.eu\/wp-content\/uploads\/2026\/04\/Soffa_sq5-900x900.jpg 900w, https:\/\/circufash.eu\/wp-content\/uploads\/2026\/04\/Soffa_sq5.jpg 1120w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/>   <\/div><\/div><h3 class=\"eut-element eut-title eut-align-center eut-animated-item eut-fade-in-up eut-duration-normal eut-h5\" style=\"\" data-delay=\"600\"><span>Soffa<\/span><\/h3>[vc_column_text css=\u00a0\u00bb.vc_custom_1776622802780{margin-bottom: 30px !important;}\u00a0\u00bb text_style=\u00a0\u00bbleader-text\u00a0\u00bb animation=\u00a0\u00bbeut-fade-in-up\u00a0\u00bb]<\/p>\n<p class=\"p1\" style=\"text-align: left;\">SOFFA est un studio de fabrication de mode \u00e9co-durable et circulaire bas\u00e9 en Gr\u00e8ce qui offre une int\u00e9gration professionnelle aux femmes survivantes victimes de la traite des \u00eatres humains \u2013 SGBV (violences sexuelles et sexistes) et aux r\u00e9fugi\u00e9es, gr\u00e2ce \u00e0 une formation professionnelle aux principes de la mode circulaire et aux processus z\u00e9ro d\u00e9chet avec des textiles recycl\u00e9s, naturels, v\u00e9g\u00e9taliens et \u00e0 base de plantes qui soutiennent la r\u00e9g\u00e9n\u00e9ration environnementale. SOFFA soutient l\u2019\u00e9cosyst\u00e8me textile local, gr\u00e2ce \u00e0 une approche holistique qui cr\u00e9e de la valeur pour toutes les parties prenantes. <\/p>\n<p>[\/vc_column_text]<div class=\"eut-element eut-align-center\"><a href=\"https:\/\/soffa.gr\/\" target=\"_blank\" rel=\"nofollow\" class=\"eut-btn eut-btn-extrasmall eut-square eut-bg-grey eut-bg-hover-primary-1\"><span>En savoir plus<\/span><\/a><\/div>[\/vc_column][vc_column width=\u00a0\u00bb1\/3&Prime; text_align=\u00a0\u00bbcenter\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1776004858521{padding-right: 10% !important;padding-left: 10% !important;}\u00a0\u00bb]<div class=\"eut-element eut-image eut-animated-item eut-fade-in-up eut-duration-normal eut-align-center\" style=\"margin-bottom: 0px;\" data-delay=\"600\">  <div class=\"eut-image-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"560\" height=\"560\" src=\"https:\/\/circufash.eu\/wp-content\/uploads\/2026\/04\/ULBS_sq5-560x560.jpg\" class=\"attachment-fildisi-eutf-small-square size-fildisi-eutf-small-square\" alt=\"\" srcset=\"https:\/\/circufash.eu\/wp-content\/uploads\/2026\/04\/ULBS_sq5-560x560.jpg 560w, https:\/\/circufash.eu\/wp-content\/uploads\/2026\/04\/ULBS_sq5-300x300.jpg 300w, https:\/\/circufash.eu\/wp-content\/uploads\/2026\/04\/ULBS_sq5-1024x1024.jpg 1024w, https:\/\/circufash.eu\/wp-content\/uploads\/2026\/04\/ULBS_sq5-150x150.jpg 150w, https:\/\/circufash.eu\/wp-content\/uploads\/2026\/04\/ULBS_sq5-768x768.jpg 768w, https:\/\/circufash.eu\/wp-content\/uploads\/2026\/04\/ULBS_sq5-900x900.jpg 900w, https:\/\/circufash.eu\/wp-content\/uploads\/2026\/04\/ULBS_sq5.jpg 1120w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/>   <\/div><\/div><h3 class=\"eut-element eut-title eut-align-center eut-animated-item eut-fade-in-up eut-duration-normal eut-h5\" style=\"\" data-delay=\"600\"><span>ULBS<\/span><\/h3>[vc_column_text css=\u00a0\u00bb.vc_custom_1776625635203{margin-bottom: 30px !important;}\u00a0\u00bb text_style=\u00a0\u00bbleader-text\u00a0\u00bb animation=\u00a0\u00bbeut-fade-in-up\u00a0\u00bb]<\/p>\n<p class=\"p1\" style=\"text-align: left;\">L\u2019Universit\u00e9 \u00ab Lucian Blaga \u00bb de Sibiu (ULBS) est l\u2019une des plus anciennes universit\u00e9s de Roumanie, avec une tradition de plus de 225 ans. L\u2019Universit\u00e9 promeut des sp\u00e9cialisations uniques dans l\u2019espace acad\u00e9mique roumain, et le haut degr\u00e9 de confiance recommande l\u2019ULBS comme une institution forte impliqu\u00e9e dans l\u2019am\u00e9lioration de la qualit\u00e9 du processus \u00e9ducatif. La promotion de programmes d\u2019\u00e9tudes dans des langues de circulation internationale, de m\u00e9thodes d\u2019enseignement bas\u00e9es sur les technologies de l\u2019information et la g\u00e9n\u00e9ralisation de la mise en \u0153uvre du Syst\u00e8me europ\u00e9en de transfert de cr\u00e9dits repr\u00e9sentent des garanties pour la consolidation du processus \u00e9ducatif.  <\/p>\n<p>[\/vc_column_text]<div class=\"eut-element eut-align-center\"><a href=\"https:\/\/www.ulbsibiu.ro\/en\/\" target=\"_blank\" rel=\"nofollow\" class=\"eut-btn eut-btn-extrasmall eut-square eut-bg-grey eut-bg-hover-primary-1\"><span>En savoir plus<\/span><\/a><\/div>[\/vc_column][\/vc_row][vc_row padding_top_multiplier=\u00a0\u00bb5x\u00a0\u00bb padding_bottom_multiplier=\u00a0\u00bb5x\u00a0\u00bb][vc_column][vc_column_text]<\/p>\n<h2 style=\"text-align: center;\"><a class=\"eut-modal-popup\" href=\"#contact-form\">Contactez-nous.<\/a><\/h2>\n<p>[\/vc_column_text]<h3 class=\"eut-element eut-title eut-align-center eut-animated-item eut-fade-in-up eut-duration-normal eut-small-text\" style=\"\" data-delay=\"400\"><span>N\u2019h\u00e9sitez pas \u00e0 nous contacter si vous avez besoin de plus d\u2019aide<\/span><\/h3>[\/vc_column][\/vc_row][vc_row][vc_column]\t\t\t<div class=\"eut-modal-element mfp-hide\" id=\"contact-form\">\r\n\t\t\t\t<div class=\"eut-section eut-modal-section\">\r\n\t\t\t\t\t<div class=\"eut-container\">\r\n\t\t\t\t\t\t<div class=\"eut-row eut-columns-gap-30\">\r\n\t\t\t\t\t\t\t<div class=\"eut-column eut-column-1\">\r\n\t\t\t\t\t\t\t[vc_row_inner][vc_column_inner width=\u00a0\u00bb1\/6&Prime;][\/vc_column_inner][vc_column_inner width=\u00a0\u00bb2\/3&Prime;]<h3 class=\"eut-element eut-title eut-align-left eut-h2\" style=\"\"><span>n\u2019h\u00e9sitez pas \u00e0 remplir<br \/>\nle formulaire ci-dessous<\/span><\/h3>[vc_column_text text_style=\u00a0\u00bbleader-text\u00a0\u00bb]Nous sommes fortement ax\u00e9s sur vos objectifs et sur l\u2019atteinte de r\u00e9sultats commerciaux sup\u00e9rieurs.[\/vc_column_text]<div class=\"eut-empty-space eut-height-1x\" style=\"\"><\/div>\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f1988-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"1988\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/fr\/wp-json\/wp\/v2\/pages\/4241#wpcf7-f1988-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"1988\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f1988-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"eut-form eut-underline\">\n\t<div class=\"eut-fields-wrapper\">\n\t\t<div>\n\t\t\t<h5>Your Name <i class=\"eut-text-primary-1\">*<\/i>\n\t\t\t<\/h5>\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div>\n\t\t\t<h5>Your Email <i class=\"eut-text-primary-1\">*<\/i>\n\t\t\t<\/h5>\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div>\n\t\t\t<h5>Your message\n\t\t\t<\/h5>\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div>\n\t\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Send your message\" \/>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n[\/vc_column_inner][vc_column_inner width=\u00a0\u00bb1\/6&Prime;][\/vc_column_inner][\/vc_row_inner]\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>M\u00eame le tout-puissant Pointing n\u2019a aucun contr\u00f4le sur les textes aveugles ; c\u2019est une vie presque non orthographique. Un jour pourtant, une petite ligne de texte aveugle du nom de Lorem Ipsum d\u00e9cida de partir pour le lointain Monde de la Grammaire. Le Big Oxmox lui a conseill\u00e9 de ne pas le faire, car il y avait des milliers de mauvaises virgules.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-4241","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00c0 propos - circufash<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/circufash.eu\/fr\/a-propos-de-nous\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c0 propos - circufash\" \/>\n<meta property=\"og:description\" content=\"M\u00eame le tout-puissant Pointing n\u2019a aucun contr\u00f4le sur les textes aveugles ; c\u2019est une vie presque non orthographique. Un jour pourtant, une petite ligne de texte aveugle du nom de Lorem Ipsum d\u00e9cida de partir pour le lointain Monde de la Grammaire. Le Big Oxmox lui a conseill\u00e9 de ne pas le faire, car il y avait des milliers de mauvaises virgules.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/circufash.eu\/fr\/a-propos-de-nous\/\" \/>\n<meta property=\"og:site_name\" content=\"circufash\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=61577380356966\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-25T10:07:14+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/circufash.eu\\\/fr\\\/a-propos-de-nous\\\/\",\"url\":\"https:\\\/\\\/circufash.eu\\\/fr\\\/a-propos-de-nous\\\/\",\"name\":\"\u00c0 propos - circufash\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/circufash.eu\\\/fr\\\/#website\"},\"datePublished\":\"2016-08-13T09:13:34+00:00\",\"dateModified\":\"2026-04-25T10:07:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/circufash.eu\\\/fr\\\/a-propos-de-nous\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/circufash.eu\\\/fr\\\/a-propos-de-nous\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/circufash.eu\\\/fr\\\/a-propos-de-nous\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/circufash.eu\\\/fr\\\/mise-en-page-encadree-de-la-page-daccueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c0 propos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/circufash.eu\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/circufash.eu\\\/fr\\\/\",\"name\":\"circufash\",\"description\":\"Circular urban fashion: Europe inclusive renaissance\",\"publisher\":{\"@id\":\"https:\\\/\\\/circufash.eu\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/circufash.eu\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/circufash.eu\\\/fr\\\/#organization\",\"name\":\"circufash\",\"url\":\"https:\\\/\\\/circufash.eu\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/circufash.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/circufash.eu\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/CIRCUFash_tagline_orange_rgb.png\",\"contentUrl\":\"https:\\\/\\\/circufash.eu\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/CIRCUFash_tagline_orange_rgb.png\",\"width\":1616,\"height\":1484,\"caption\":\"circufash\"},\"image\":{\"@id\":\"https:\\\/\\\/circufash.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=61577380356966\",\"https:\\\/\\\/www.instagram.com\\\/circufash\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/circufash\\\/posts\\\/?feedView=all\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c0 propos - circufash","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/circufash.eu\/fr\/a-propos-de-nous\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00c0 propos - circufash","og_description":"M\u00eame le tout-puissant Pointing n\u2019a aucun contr\u00f4le sur les textes aveugles ; c\u2019est une vie presque non orthographique. Un jour pourtant, une petite ligne de texte aveugle du nom de Lorem Ipsum d\u00e9cida de partir pour le lointain Monde de la Grammaire. Le Big Oxmox lui a conseill\u00e9 de ne pas le faire, car il y avait des milliers de mauvaises virgules.","og_url":"https:\/\/circufash.eu\/fr\/a-propos-de-nous\/","og_site_name":"circufash","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=61577380356966","article_modified_time":"2026-04-25T10:07:14+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/circufash.eu\/fr\/a-propos-de-nous\/","url":"https:\/\/circufash.eu\/fr\/a-propos-de-nous\/","name":"\u00c0 propos - circufash","isPartOf":{"@id":"https:\/\/circufash.eu\/fr\/#website"},"datePublished":"2016-08-13T09:13:34+00:00","dateModified":"2026-04-25T10:07:14+00:00","breadcrumb":{"@id":"https:\/\/circufash.eu\/fr\/a-propos-de-nous\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/circufash.eu\/fr\/a-propos-de-nous\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/circufash.eu\/fr\/a-propos-de-nous\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/circufash.eu\/fr\/mise-en-page-encadree-de-la-page-daccueil\/"},{"@type":"ListItem","position":2,"name":"\u00c0 propos"}]},{"@type":"WebSite","@id":"https:\/\/circufash.eu\/fr\/#website","url":"https:\/\/circufash.eu\/fr\/","name":"circufash","description":"Circular urban fashion: Europe inclusive renaissance","publisher":{"@id":"https:\/\/circufash.eu\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/circufash.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/circufash.eu\/fr\/#organization","name":"circufash","url":"https:\/\/circufash.eu\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/circufash.eu\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/circufash.eu\/wp-content\/uploads\/2026\/05\/CIRCUFash_tagline_orange_rgb.png","contentUrl":"https:\/\/circufash.eu\/wp-content\/uploads\/2026\/05\/CIRCUFash_tagline_orange_rgb.png","width":1616,"height":1484,"caption":"circufash"},"image":{"@id":"https:\/\/circufash.eu\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61577380356966","https:\/\/www.instagram.com\/circufash\/","https:\/\/www.linkedin.com\/company\/circufash\/posts\/?feedView=all"]}]}},"_links":{"self":[{"href":"https:\/\/circufash.eu\/fr\/wp-json\/wp\/v2\/pages\/4241","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/circufash.eu\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/circufash.eu\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/circufash.eu\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/circufash.eu\/fr\/wp-json\/wp\/v2\/comments?post=4241"}],"version-history":[{"count":15,"href":"https:\/\/circufash.eu\/fr\/wp-json\/wp\/v2\/pages\/4241\/revisions"}],"predecessor-version":[{"id":4557,"href":"https:\/\/circufash.eu\/fr\/wp-json\/wp\/v2\/pages\/4241\/revisions\/4557"}],"wp:attachment":[{"href":"https:\/\/circufash.eu\/fr\/wp-json\/wp\/v2\/media?parent=4241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}